{"id":240,"date":"2017-02-17T12:40:49","date_gmt":"2017-02-17T11:40:49","guid":{"rendered":"http:\/\/mxajfmgl.preview.infomaniak.website\/?post_type=project&#038;p=240"},"modified":"2026-06-08T10:55:27","modified_gmt":"2026-06-08T08:55:27","slug":"vue-a-360","status":"publish","type":"project","link":"https:\/\/ileauxnattes.net\/en\/project\/vue-a-360\/","title":{"rendered":"VUE \u00e0 360\u00b0"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.27.5&#8243; background_image=&#8221;https:\/\/ileauxnattes.net\/wp-content\/uploads\/2024\/02\/TERRASSE-LMB-scaled.jpg&#8221; min_height=&#8221;659px&#8221; height=&#8221;670px&#8221; max_height=&#8221;100px&#8221; custom_padding=&#8221;1px||13px|||&#8221; transparent_background=&#8221;off&#8221; make_fullwidth=&#8221;off&#8221; use_custom_width=&#8221;off&#8221; width_unit=&#8221;off&#8221; custom_width_px=&#8221;1080px&#8221; custom_width_percent=&#8221;80%&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.27.4&#8243; max_width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; min_height=&#8221;1615.8px&#8221; custom_padding=&#8221;15px||11px|||&#8221; border_width_all=&#8221;0.5px&#8221; transparent_background=&#8221;off&#8221; make_fullwidth=&#8221;off&#8221; use_custom_width=&#8221;off&#8221; width_unit=&#8221;off&#8221; custom_width_px=&#8221;1080px&#8221; custom_width_percent=&#8221;80%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;4&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;2560px&#8221; custom_padding=&#8221;7px||6px|1px||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_accordion _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; toggle_text_align=&#8221;center&#8221; width=&#8221;100%&#8221; custom_margin=&#8221;||4px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_accordion_item title=&#8221;Trois Terrasses avec vue panoramique \u00e0 360\u00b0&#8221; open=&#8221;on&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; toggle_level=&#8221;h3&#8243; toggle_font=&#8221;Tangerine||||||||&#8221; toggle_font_size=&#8221;66px&#8221;][\/et_pb_accordion_item][\/et_pb_accordion][et_pb_image src=&#8221;https:\/\/ileauxnattes.net\/wp-content\/uploads\/2025\/12\/La-Maison-Blanche-Terrasse-vue-a-360\u00b0-2.png&#8221; title_text=&#8221;La Maison Blanche &#8211; Terrasse vue \u00e0 360\u00b0&#8221; force_fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||23px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; admin_label=&#8221;row&#8221; _builder_version=&#8221;4.27.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;100%&#8221; max_width=&#8221;2560px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px|9px||0px|false|false&#8221; custom_padding=&#8221;8px|0px|0px|0px|false|false&#8221; make_fullwidth=&#8221;off&#8221; use_custom_width=&#8221;off&#8221; width_unit=&#8221;off&#8221; custom_width_px=&#8221;1080px&#8221; custom_width_percent=&#8221;80%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/ileauxnattes.net\/wp-content\/uploads\/2026\/06\/2026-LMB-Bar-1.jpg&#8221; title_text=&#8221;2026 LMB Bar&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;|-38px||||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_image src=&#8221;https:\/\/ileauxnattes.net\/wp-content\/uploads\/2026\/06\/2026-LMB-Bar-int-.jpg&#8221; title_text=&#8221;2026 LMB Bar int&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; min_height=&#8221;100px&#8221; custom_margin=&#8221;|-38px||||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_accordion _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; toggle_level=&#8221;h2&#8243; toggle_text_align=&#8221;center&#8221; body_text_align=&#8221;right&#8221; body_text_color=&#8221;#000000&#8243; body_font_size=&#8221;33px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_accordion_item open=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;Gentium Book Plus||||||||&#8221; body_font_size=&#8221;38px&#8221; body_letter_spacing=&#8221;3px&#8221; body_line_height=&#8221;1.8em&#8221; body_font_size_last_edited=&#8221;off|desktop&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221; toggle_level=&#8221;h1&#8243; toggle_font=&#8221;Gentium Book Plus||||||||&#8221; toggle_font_size=&#8221;36px&#8221;][\/et_pb_accordion_item][\/et_pb_accordion][et_pb_accordion _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; toggle_level=&#8221;h2&#8243; toggle_text_align=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_accordion_item title=&#8221;Ouvert de 07h00 \u00e0 18h30&#8243; open=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;Gentium Book Plus||||||||&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;1.6em&#8221; body_font_size_last_edited=&#8221;off|desktop&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221; toggle_level=&#8221;h1&#8243; toggle_font=&#8221;Gentium Book Plus||||||||&#8221; toggle_font_size=&#8221;36px&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>\u00a0Entr\u00e9e de 10&#8217;000 Ariary <\/strong>par personne<\/p>\n<div style=\"text-align: center;\">\n<p>Le *LMB Bar* vous propose un service de boissons et de snacks\u00a0typiques nattiens<br \/>que vous pouvez consommer sur les terrasses au 3\u00e8me,<br \/>en salle, au bar <span>ou sur la nouvelle terrasse ext\u00e9rieure au 2\u00e8me \u00e9tage,<br \/>qui se situe en prolongation du *LMB Bar*.<br \/><\/span><\/p>\n<\/div>\n<div style=\"text-align: center;\">\n<p>On vous souhaite de passer un agr\u00e9able moment de d\u00e9tente<br \/>ou vous grignotez, vous d\u00e9gustez, tout en admirant la vue.<\/p>\n<\/div>\n<p style=\"text-align: center;\">Vous \u00eates au-dessus de la canop\u00e9e natienne et profitez :<br \/>d&#8217;une vue incroyable sur l&#8217;\u00eele de Sainte-Marie, au nord &#8211; sur l&#8217;\u00eele aux Nattes \u00e0 360\u00b0 &#8211;<br \/>sur les \u00eelots aux Sables, au nord-est &#8211; sur le grand lagon et la barri\u00e8re de corail, du sud nattien &#8211; sur la grande \u00eele de Madagascar, \u00e0 l&#8217;ouest<\/p>\n<p style=\"text-align: center;\">En plus, vous pouvez observer depuis les terrasses :<br \/>le lever ou le coucher de soleil, le lever ou le coucher de lune<br \/>le ciel \u00e9toil\u00e9 et la voie lact\u00e9e, des baleines, en saison<\/p>\n<p style=\"text-align: center;\">(selon nos heures d&#8217;ouvertures pour les visites)<br \/><strong>Quelque soit la m\u00e9t\u00e9o, l&#8217;\u00e9tablissement est ouvert.<\/strong><\/p>\n<p>[\/et_pb_accordion_item][\/et_pb_accordion][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/ileauxnattes.net\/wp-content\/uploads\/2026\/06\/2026-LMB-Bar-.jpg&#8221; title_text=&#8221;2026 LMB Bar-&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; height=&#8221;285px&#8221; max_height=&#8221;283px&#8221; custom_padding=&#8221;25px||10px|0px||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_image src=&#8221;https:\/\/ileauxnattes.net\/wp-content\/uploads\/2025\/12\/La-Maison-Blanche-ile-aux-Nattes-LMB-BAR-vue-sur-Sainte-Marie-.jpg&#8221; title_text=&#8221;La Maison Blanche ile aux Nattes, LMB-BAR-vue sur Sainte-Marie-&#8221; align=&#8221;center&#8221; admin_label=&#8221;La nouvelle embl\u00e8me semble fumer les nuages&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||12px|72px||&#8221; custom_padding=&#8221;||0px|0px||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.24.2&#8243; custom_padding=&#8221;0px||8px|||&#8221; transparent_background=&#8221;off&#8221; make_fullwidth=&#8221;off&#8221; use_custom_width=&#8221;off&#8221; width_unit=&#8221;off&#8221; custom_width_px=&#8221;1080px&#8221; custom_width_percent=&#8221;80%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; make_equal=&#8221;on&#8221; admin_label=&#8221;row&#8221; _builder_version=&#8221;4.24.2&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;100%&#8221; max_width=&#8221;2560px&#8221; custom_padding=&#8221;10px|0px|0px|0px||&#8221; make_fullwidth=&#8221;off&#8221; use_custom_width=&#8221;off&#8221; width_unit=&#8221;off&#8221; custom_width_px=&#8221;1080px&#8221; custom_width_percent=&#8221;80%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/ileauxnattes.net\/wp-content\/uploads\/2017\/02\/Vue-sur-le-lagon-sud-de-la-terrasse-3eme.png&#8221; title_text=&#8221;Vue sur le lagon sud de la terrasse 3\u00e8me&#8221; show_in_lightbox=&#8221;on&#8221; align=&#8221;center&#8221; force_fullwidth=&#8221;on&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;center&#8221; align_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Image&#8221; _builder_version=&#8221;4.24.2&#8243; custom_margin=&#8221;||-7px|||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_duration=&#8221;500ms&#8221; animation_intensity_slide=&#8221;10%&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_width=&#8221;1px&#8221; border_style=&#8221;solid&#8221; sticky=&#8221;off&#8221; always_center_on_mobile=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8221;on&#8221; make_equal=&#8221;on&#8221; admin_label=&#8221;row&#8221; _builder_version=&#8221;4.24.2&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;100%&#8221; max_width=&#8221;2560px&#8221; custom_padding=&#8221;15px|0px|6px|0px||&#8221; make_fullwidth=&#8221;off&#8221; use_custom_width=&#8221;off&#8221; width_unit=&#8221;off&#8221; custom_width_px=&#8221;1080px&#8221; custom_width_percent=&#8221;80%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;16px&#8221; min_height=&#8221;18.8px&#8221; custom_margin=&#8221;||10px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Vue depuis La Maison Blanche sur le phare Blevec de l&#8217;ile aux Nattes<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/ileauxnattes.net\/wp-content\/uploads\/2026\/06\/2026-La-Maison-Blanche-ile-aux-nattes-1.jpg&#8221; title_text=&#8221;2026 La Maison Blanche ile aux nattes&#8221; show_in_lightbox=&#8221;on&#8221; align=&#8221;center&#8221; force_fullwidth=&#8221;on&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;center&#8221; align_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Image&#8221; _builder_version=&#8221;4.27.5&#8243; custom_margin=&#8221;||3px|||&#8221; custom_padding=&#8221;14px|||||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_duration=&#8221;500ms&#8221; animation_intensity_slide=&#8221;10%&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_width=&#8221;1px&#8221; border_style=&#8221;solid&#8221; sticky=&#8221;off&#8221; always_center_on_mobile=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;16px&#8221; custom_margin=&#8221;-7px||4px|||&#8221; custom_padding=&#8221;12px||8px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>2026 Vue par drone lors d&#8217;une soir\u00e9e sp\u00e9ciale anniversaire \u00e0 La Maison Blanche de l&#8217;\u00eele aux Nattes<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Entr\u00e9e de 10&#8217;000 Ariary par personne Le *LMB Bar* vous propose un service de boissons et de snacks\u00a0typiques nattiensque vous pouvez consommer sur les terrasses au 3\u00e8me,en salle, au bar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":29046,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"project_category":[10],"project_tag":[],"class_list":["post-240","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-terrasses"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Trois Terrasses avec vue panoramique \u00e0 360\u00b0 Ouvert de 07h00 \u00e0 18h30 Entr\u00e9e de 10\u2019000 Ariary par personne Le *LMB Bar* vous propose un service de boissons et de snacks typiques nattiensque vous pouvez consommer sur les terrasses au 3\u00e8me,en salle, au bar ou sur la nouvelle terrasse ext\u00e9rieure au 2\u00e8me \u00e9tage,qui se situe en prolongation\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"ileaux\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ileauxnattes.net\/en\/project\/vue-a-360\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"LA MAISON BLANCHE ILE AUX NATTES - La Maison Blanche\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"VUE \u00e0 360\u00b0 - LA MAISON BLANCHE ILE AUX NATTES\" \/>\n\t\t<meta property=\"og:description\" content=\"Trois Terrasses avec vue panoramique \u00e0 360\u00b0 Ouvert de 07h00 \u00e0 18h30 Entr\u00e9e de 10\u2019000 Ariary par personne Le *LMB Bar* vous propose un service de boissons et de snacks typiques nattiensque vous pouvez consommer sur les terrasses au 3\u00e8me,en salle, au bar ou sur la nouvelle terrasse ext\u00e9rieure au 2\u00e8me \u00e9tage,qui se situe en prolongation\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ileauxnattes.net\/en\/project\/vue-a-360\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-02-17T11:40:49+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-08T08:55:27+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"VUE \u00e0 360\u00b0 - LA MAISON BLANCHE ILE AUX NATTES\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Trois Terrasses avec vue panoramique \u00e0 360\u00b0 Ouvert de 07h00 \u00e0 18h30 Entr\u00e9e de 10\u2019000 Ariary par personne Le *LMB Bar* vous propose un service de boissons et de snacks typiques nattiensque vous pouvez consommer sur les terrasses au 3\u00e8me,en salle, au bar ou sur la nouvelle terrasse ext\u00e9rieure au 2\u00e8me \u00e9tage,qui se situe en prolongation\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/project\\\/vue-a-360\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en#listItem\",\"position\":1,\"name\":\"Domicile\",\"item\":\"https:\\\/\\\/ileauxnattes.net\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/project\\\/#listItem\",\"name\":\"Projects\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/project\\\/#listItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/project\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/project_category\\\/terrasses\\\/#listItem\",\"name\":\"Terrasses\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en#listItem\",\"name\":\"Domicile\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/project_category\\\/terrasses\\\/#listItem\",\"position\":3,\"name\":\"Terrasses\",\"item\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/project_category\\\/terrasses\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/project\\\/vue-a-360\\\/#listItem\",\"name\":\"VUE \\u00e0 360\\u00b0\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/project\\\/#listItem\",\"name\":\"Projects\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/project\\\/vue-a-360\\\/#listItem\",\"position\":4,\"name\":\"VUE \\u00e0 360\\u00b0\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/project_category\\\/terrasses\\\/#listItem\",\"name\":\"Terrasses\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/#organization\",\"name\":\"[:fr]LA MAISON BLANCHE ILE AUX NATTES[:]\",\"description\":\"La Maison Blanche\",\"url\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/\",\"telephone\":\"+261324008432\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/author\\\/ileaux\\\/#author\",\"url\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/author\\\/ileaux\\\/\",\"name\":\"ileaux\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/project\\\/vue-a-360\\\/#webpage\",\"url\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/project\\\/vue-a-360\\\/\",\"name\":\"VUE \\u00e0 360\\u00b0 - LA MAISON BLANCHE ILE AUX NATTES\",\"description\":\"Trois Terrasses avec vue panoramique \\u00e0 360\\u00b0 Ouvert de 07h00 \\u00e0 18h30 Entr\\u00e9e de 10\\u2019000 Ariary par personne Le *LMB Bar* vous propose un service de boissons et de snacks typiques nattiensque vous pouvez consommer sur les terrasses au 3\\u00e8me,en salle, au bar ou sur la nouvelle terrasse ext\\u00e9rieure au 2\\u00e8me \\u00e9tage,qui se situe en prolongation\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/project\\\/vue-a-360\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/author\\\/ileaux\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/author\\\/ileaux\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ileauxnattes.net\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/TERRASSE-LMB-scaled.jpg\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/project\\\/vue-a-360\\\/#mainImage\",\"width\":2560,\"height\":621},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/project\\\/vue-a-360\\\/#mainImage\"},\"datePublished\":\"2017-02-17T12:40:49+01:00\",\"dateModified\":\"2026-06-08T10:55:27+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/\",\"name\":\"[:fr]LA MAISON BLANCHE ILE AUX NATTES[:]\",\"description\":\"La Maison Blanche\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"VUE \u00e0 360\u00b0 - LA MAISON BLANCHE ILE AUX NATTES","description":"Trois Terrasses avec vue panoramique \u00e0 360\u00b0 Ouvert de 07h00 \u00e0 18h30 Entr\u00e9e de 10\u2019000 Ariary par personne Le *LMB Bar* vous propose un service de boissons et de snacks typiques nattiensque vous pouvez consommer sur les terrasses au 3\u00e8me,en salle, au bar ou sur la nouvelle terrasse ext\u00e9rieure au 2\u00e8me \u00e9tage,qui se situe en prolongation","canonical_url":"https:\/\/ileauxnattes.net\/en\/project\/vue-a-360\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ileauxnattes.net\/en\/project\/vue-a-360\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ileauxnattes.net\/en#listItem","position":1,"name":"Domicile","item":"https:\/\/ileauxnattes.net\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ileauxnattes.net\/en\/project\/#listItem","name":"Projects"}},{"@type":"ListItem","@id":"https:\/\/ileauxnattes.net\/en\/project\/#listItem","position":2,"name":"Projects","item":"https:\/\/ileauxnattes.net\/en\/project\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ileauxnattes.net\/en\/project_category\/terrasses\/#listItem","name":"Terrasses"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ileauxnattes.net\/en#listItem","name":"Domicile"}},{"@type":"ListItem","@id":"https:\/\/ileauxnattes.net\/en\/project_category\/terrasses\/#listItem","position":3,"name":"Terrasses","item":"https:\/\/ileauxnattes.net\/en\/project_category\/terrasses\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ileauxnattes.net\/en\/project\/vue-a-360\/#listItem","name":"VUE \u00e0 360\u00b0"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ileauxnattes.net\/en\/project\/#listItem","name":"Projects"}},{"@type":"ListItem","@id":"https:\/\/ileauxnattes.net\/en\/project\/vue-a-360\/#listItem","position":4,"name":"VUE \u00e0 360\u00b0","previousItem":{"@type":"ListItem","@id":"https:\/\/ileauxnattes.net\/en\/project_category\/terrasses\/#listItem","name":"Terrasses"}}]},{"@type":"Organization","@id":"https:\/\/ileauxnattes.net\/en\/#organization","name":"[:fr]LA MAISON BLANCHE ILE AUX NATTES[:]","description":"La Maison Blanche","url":"https:\/\/ileauxnattes.net\/en\/","telephone":"+261324008432"},{"@type":"Person","@id":"https:\/\/ileauxnattes.net\/en\/author\/ileaux\/#author","url":"https:\/\/ileauxnattes.net\/en\/author\/ileaux\/","name":"ileaux"},{"@type":"WebPage","@id":"https:\/\/ileauxnattes.net\/en\/project\/vue-a-360\/#webpage","url":"https:\/\/ileauxnattes.net\/en\/project\/vue-a-360\/","name":"VUE \u00e0 360\u00b0 - LA MAISON BLANCHE ILE AUX NATTES","description":"Trois Terrasses avec vue panoramique \u00e0 360\u00b0 Ouvert de 07h00 \u00e0 18h30 Entr\u00e9e de 10\u2019000 Ariary par personne Le *LMB Bar* vous propose un service de boissons et de snacks typiques nattiensque vous pouvez consommer sur les terrasses au 3\u00e8me,en salle, au bar ou sur la nouvelle terrasse ext\u00e9rieure au 2\u00e8me \u00e9tage,qui se situe en prolongation","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ileauxnattes.net\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ileauxnattes.net\/en\/project\/vue-a-360\/#breadcrumblist"},"author":{"@id":"https:\/\/ileauxnattes.net\/en\/author\/ileaux\/#author"},"creator":{"@id":"https:\/\/ileauxnattes.net\/en\/author\/ileaux\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ileauxnattes.net\/wp-content\/uploads\/2024\/02\/TERRASSE-LMB-scaled.jpg","@id":"https:\/\/ileauxnattes.net\/en\/project\/vue-a-360\/#mainImage","width":2560,"height":621},"primaryImageOfPage":{"@id":"https:\/\/ileauxnattes.net\/en\/project\/vue-a-360\/#mainImage"},"datePublished":"2017-02-17T12:40:49+01:00","dateModified":"2026-06-08T10:55:27+02:00"},{"@type":"WebSite","@id":"https:\/\/ileauxnattes.net\/en\/#website","url":"https:\/\/ileauxnattes.net\/en\/","name":"[:fr]LA MAISON BLANCHE ILE AUX NATTES[:]","description":"La Maison Blanche","inLanguage":"en-US","publisher":{"@id":"https:\/\/ileauxnattes.net\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"LA MAISON BLANCHE ILE AUX NATTES - La Maison Blanche","og:type":"article","og:title":"VUE \u00e0 360\u00b0 - LA MAISON BLANCHE ILE AUX NATTES","og:description":"Trois Terrasses avec vue panoramique \u00e0 360\u00b0 Ouvert de 07h00 \u00e0 18h30 Entr\u00e9e de 10\u2019000 Ariary par personne Le *LMB Bar* vous propose un service de boissons et de snacks typiques nattiensque vous pouvez consommer sur les terrasses au 3\u00e8me,en salle, au bar ou sur la nouvelle terrasse ext\u00e9rieure au 2\u00e8me \u00e9tage,qui se situe en prolongation","og:url":"https:\/\/ileauxnattes.net\/en\/project\/vue-a-360\/","article:published_time":"2017-02-17T11:40:49+00:00","article:modified_time":"2026-06-08T08:55:27+00:00","twitter:card":"summary_large_image","twitter:title":"VUE \u00e0 360\u00b0 - LA MAISON BLANCHE ILE AUX NATTES","twitter:description":"Trois Terrasses avec vue panoramique \u00e0 360\u00b0 Ouvert de 07h00 \u00e0 18h30 Entr\u00e9e de 10\u2019000 Ariary par personne Le *LMB Bar* vous propose un service de boissons et de snacks typiques nattiensque vous pouvez consommer sur les terrasses au 3\u00e8me,en salle, au bar ou sur la nouvelle terrasse ext\u00e9rieure au 2\u00e8me \u00e9tage,qui se situe en prolongation"},"aioseo_meta_data":{"post_id":"240","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2024-03-21 11:20:38","updated":"2026-06-08 09:02:15","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ileauxnattes.net\/en\" title=\"Domicile\">Domicile<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ileauxnattes.net\/en\/project\/\" title=\"Projects\">Projects<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ileauxnattes.net\/en\/project_category\/terrasses\/\" title=\"Terrasses\">Terrasses<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tVUE \u00e0 360\u00b0\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Domicile","link":"https:\/\/ileauxnattes.net\/en"},{"label":"Projects","link":"https:\/\/ileauxnattes.net\/en\/project\/"},{"label":"Terrasses","link":"https:\/\/ileauxnattes.net\/en\/project_category\/terrasses\/"},{"label":"VUE \u00e0 360\u00b0","link":"https:\/\/ileauxnattes.net\/en\/project\/vue-a-360\/"}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ileauxnattes.net\/en\/wp-json\/wp\/v2\/project\/240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ileauxnattes.net\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/ileauxnattes.net\/en\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/ileauxnattes.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ileauxnattes.net\/en\/wp-json\/wp\/v2\/comments?post=240"}],"version-history":[{"count":62,"href":"https:\/\/ileauxnattes.net\/en\/wp-json\/wp\/v2\/project\/240\/revisions"}],"predecessor-version":[{"id":31161,"href":"https:\/\/ileauxnattes.net\/en\/wp-json\/wp\/v2\/project\/240\/revisions\/31161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ileauxnattes.net\/en\/wp-json\/wp\/v2\/media\/29046"}],"wp:attachment":[{"href":"https:\/\/ileauxnattes.net\/en\/wp-json\/wp\/v2\/media?parent=240"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/ileauxnattes.net\/en\/wp-json\/wp\/v2\/project_category?post=240"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/ileauxnattes.net\/en\/wp-json\/wp\/v2\/project_tag?post=240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}