{"id":30629,"date":"2024-03-18T21:28:59","date_gmt":"2024-03-18T20:28:59","guid":{"rendered":"https:\/\/ileauxnattes.net\/?page_id=30629"},"modified":"2025-12-08T20:15:45","modified_gmt":"2025-12-08T19:15:45","slug":"contact-2","status":"publish","type":"page","link":"https:\/\/ileauxnattes.net\/de\/contact-2\/","title":{"rendered":"CONTACT"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; background_image=&#8220;https:\/\/ileauxnattes.net\/wp-content\/uploads\/2025\/12\/La-Maison-Blanche-vue-panoramique.jpg&#8220; width=&#8220;100%&#8220; module_alignment=&#8220;center&#8220; min_height=&#8220;508px&#8220; height=&#8220;461px&#8220; max_height=&#8220;463px&#8220; custom_margin=&#8220;-48px||6px||false|false&#8220; custom_padding=&#8220;184px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_post_title _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; title_level=&#8220;h3&#8243; title_font=&#8220;Tangerine||||||||&#8220; title_text_color=&#8220;#FFFFFF&#8220; title_font_size=&#8220;39px&#8220; title_letter_spacing=&#8220;2px&#8220; sticky_enabled=&#8220;0&#8243;][\/et_pb_post_title][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;11px||17px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; max_width=&#8220;2560px&#8220; custom_padding=&#8220;13px||12px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/ileauxnattes.net\/wp-content\/uploads\/2025\/12\/Bienvenue-a-La-Maison-Blanche-ile-aux-Nattes-scaled.jpg&#8220; title_text=&#8220;Bienvenue \u00e0 La Maison Blanche &#8211; ile aux Nattes&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; width=&#8220;75%&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;|9px||||&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/ileauxnattes.net\/wp-content\/uploads\/2025\/12\/Ravinala-du-jardin-de-La-Maison-BLanche-.png&#8220; alt=&#8220;%22MyzmbvideosDMBGLMB20252025 PHOTO WEBRavinala du jardin de La Maison BLanche .png%22&#8243; title_text=&#8220;Ravinala du jardin de La Maison BLanche&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; module_alignment=&#8220;center&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/ileauxnattes.net\/wp-content\/uploads\/2025\/12\/La-Maison-Blanche-ile-aux-Nattes-rez-1-1.png&#8220; title_text=&#8220;La Maison Blanche ile aux Nattes-rez-&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; module_alignment=&#8220;center&#8220; min_height=&#8220;342px&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_accordion _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; toggle_level=&#8220;h3&#8243; toggle_font=&#8220;Tangerine||||||||&#8220; toggle_text_align=&#8220;center&#8220; toggle_font_size=&#8220;34px&#8220; toggle_line_height=&#8220;1.1em&#8220; body_text_align=&#8220;center&#8220; body_font_size=&#8220;18px&#8220; body_line_height=&#8220;1.4em&#8220; width=&#8220;100%&#8220; custom_margin=&#8220;-11px|||||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_accordion_item title=&#8220;La Maison Blanche &#8211; \u00cele aux Nattes&#8220; open=&#8220;on&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h4>Colline du village d&#8217;Agniribe<\/h4>\n<h4>\u00cele aux Nattes<\/h4>\n<h4>515 Sainte-Marie<\/h4>\n<h4>Madagascar<\/h4>\n<h4><\/h4>\n<div>\n<h6>T\u00e9l. Orange+261(0) 32 400 84 32<\/h6>\n<h6><span style=\"color: #16a085; font-family: trebuchet ms, helvetica, sans-serif;\"><u>lamaisonblanche@ileauxnattes.net<\/u><\/span><\/h6>\n<\/div>\n<div><\/div>\n<div><\/div>\n<p>[\/et_pb_accordion_item][\/et_pb_accordion][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Colline du village d&#8217;Agniribe \u00cele aux Nattes 515 Sainte-Marie Madagascar T\u00e9l. Orange+261(0) 32 400 84 32 lamaisonblanche@ileauxnattes.net<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"class_list":["post-30629","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"CONTACT von ileaux | M\u00e4rz 18, 2024 La Maison Blanche - \u00cele aux Nattes Colline du village d\u2019Agniribe \u00cele aux Nattes 515 Sainte-Marie Madagascar T\u00e9l. Orange+261(0) 32 400 84 32 lamaisonblanche@ileauxnattes.net\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ileauxnattes.net\/de\/contact-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"LA MAISON BLANCHE ILE AUX NATTES - La Maison Blanche\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"CONTACT - LA MAISON BLANCHE ILE AUX NATTES\" \/>\n\t\t<meta property=\"og:description\" content=\"CONTACT von ileaux | M\u00e4rz 18, 2024 La Maison Blanche - \u00cele aux Nattes Colline du village d\u2019Agniribe \u00cele aux Nattes 515 Sainte-Marie Madagascar T\u00e9l. Orange+261(0) 32 400 84 32 lamaisonblanche@ileauxnattes.net\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ileauxnattes.net\/de\/contact-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-03-18T20:28:59+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-12-08T19:15:45+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"CONTACT - LA MAISON BLANCHE ILE AUX NATTES\" \/>\n\t\t<meta name=\"twitter:description\" content=\"CONTACT von ileaux | M\u00e4rz 18, 2024 La Maison Blanche - \u00cele aux Nattes Colline du village d\u2019Agniribe \u00cele aux Nattes 515 Sainte-Marie Madagascar T\u00e9l. Orange+261(0) 32 400 84 32 lamaisonblanche@ileauxnattes.net\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/de\\\/contact-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/de#listItem\",\"position\":1,\"name\":\"Domicile\",\"item\":\"https:\\\/\\\/ileauxnattes.net\\\/de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/de\\\/contact-2\\\/#listItem\",\"name\":\"CONTACT\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/de\\\/contact-2\\\/#listItem\",\"position\":2,\"name\":\"CONTACT\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/de#listItem\",\"name\":\"Domicile\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/de\\\/#organization\",\"name\":\"[:fr]LA MAISON BLANCHE ILE AUX NATTES[:]\",\"description\":\"La Maison Blanche\",\"url\":\"https:\\\/\\\/ileauxnattes.net\\\/de\\\/\",\"telephone\":\"+261324008432\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/de\\\/contact-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ileauxnattes.net\\\/de\\\/contact-2\\\/\",\"name\":\"CONTACT - LA MAISON BLANCHE ILE AUX NATTES\",\"description\":\"CONTACT von ileaux | M\\u00e4rz 18, 2024 La Maison Blanche - \\u00cele aux Nattes Colline du village d\\u2019Agniribe \\u00cele aux Nattes 515 Sainte-Marie Madagascar T\\u00e9l. Orange+261(0) 32 400 84 32 lamaisonblanche@ileauxnattes.net\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/de\\\/contact-2\\\/#breadcrumblist\"},\"datePublished\":\"2024-03-18T21:28:59+01:00\",\"dateModified\":\"2025-12-08T20:15:45+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/ileauxnattes.net\\\/de\\\/\",\"name\":\"[:fr]LA MAISON BLANCHE ILE AUX NATTES[:]\",\"description\":\"La Maison Blanche\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/ileauxnattes.net\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"CONTACT - LA MAISON BLANCHE ILE AUX NATTES","description":"CONTACT von ileaux | M\u00e4rz 18, 2024 La Maison Blanche - \u00cele aux Nattes Colline du village d\u2019Agniribe \u00cele aux Nattes 515 Sainte-Marie Madagascar T\u00e9l. Orange+261(0) 32 400 84 32 lamaisonblanche@ileauxnattes.net","canonical_url":"https:\/\/ileauxnattes.net\/de\/contact-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ileauxnattes.net\/de\/contact-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ileauxnattes.net\/de#listItem","position":1,"name":"Domicile","item":"https:\/\/ileauxnattes.net\/de","nextItem":{"@type":"ListItem","@id":"https:\/\/ileauxnattes.net\/de\/contact-2\/#listItem","name":"CONTACT"}},{"@type":"ListItem","@id":"https:\/\/ileauxnattes.net\/de\/contact-2\/#listItem","position":2,"name":"CONTACT","previousItem":{"@type":"ListItem","@id":"https:\/\/ileauxnattes.net\/de#listItem","name":"Domicile"}}]},{"@type":"Organization","@id":"https:\/\/ileauxnattes.net\/de\/#organization","name":"[:fr]LA MAISON BLANCHE ILE AUX NATTES[:]","description":"La Maison Blanche","url":"https:\/\/ileauxnattes.net\/de\/","telephone":"+261324008432"},{"@type":"WebPage","@id":"https:\/\/ileauxnattes.net\/de\/contact-2\/#webpage","url":"https:\/\/ileauxnattes.net\/de\/contact-2\/","name":"CONTACT - LA MAISON BLANCHE ILE AUX NATTES","description":"CONTACT von ileaux | M\u00e4rz 18, 2024 La Maison Blanche - \u00cele aux Nattes Colline du village d\u2019Agniribe \u00cele aux Nattes 515 Sainte-Marie Madagascar T\u00e9l. Orange+261(0) 32 400 84 32 lamaisonblanche@ileauxnattes.net","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/ileauxnattes.net\/de\/#website"},"breadcrumb":{"@id":"https:\/\/ileauxnattes.net\/de\/contact-2\/#breadcrumblist"},"datePublished":"2024-03-18T21:28:59+01:00","dateModified":"2025-12-08T20:15:45+01:00"},{"@type":"WebSite","@id":"https:\/\/ileauxnattes.net\/de\/#website","url":"https:\/\/ileauxnattes.net\/de\/","name":"[:fr]LA MAISON BLANCHE ILE AUX NATTES[:]","description":"La Maison Blanche","inLanguage":"de-DE","publisher":{"@id":"https:\/\/ileauxnattes.net\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"LA MAISON BLANCHE ILE AUX NATTES - La Maison Blanche","og:type":"article","og:title":"CONTACT - LA MAISON BLANCHE ILE AUX NATTES","og:description":"CONTACT von ileaux | M\u00e4rz 18, 2024 La Maison Blanche - \u00cele aux Nattes Colline du village d\u2019Agniribe \u00cele aux Nattes 515 Sainte-Marie Madagascar T\u00e9l. Orange+261(0) 32 400 84 32 lamaisonblanche@ileauxnattes.net","og:url":"https:\/\/ileauxnattes.net\/de\/contact-2\/","article:published_time":"2024-03-18T20:28:59+00:00","article:modified_time":"2025-12-08T19:15:45+00:00","twitter:card":"summary_large_image","twitter:title":"CONTACT - LA MAISON BLANCHE ILE AUX NATTES","twitter:description":"CONTACT von ileaux | M\u00e4rz 18, 2024 La Maison Blanche - \u00cele aux Nattes Colline du village d\u2019Agniribe \u00cele aux Nattes 515 Sainte-Marie Madagascar T\u00e9l. Orange+261(0) 32 400 84 32 lamaisonblanche@ileauxnattes.net"},"aioseo_meta_data":{"post_id":"30629","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2024-03-21 11:18:22","updated":"2025-12-08 19:22:07","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ileauxnattes.net\/de\" title=\"Domicile\">Domicile<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCONTACT\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Domicile","link":"https:\/\/ileauxnattes.net\/de"},{"label":"CONTACT","link":"https:\/\/ileauxnattes.net\/de\/contact-2\/"}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ileauxnattes.net\/de\/wp-json\/wp\/v2\/pages\/30629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ileauxnattes.net\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ileauxnattes.net\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ileauxnattes.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ileauxnattes.net\/de\/wp-json\/wp\/v2\/comments?post=30629"}],"version-history":[{"count":10,"href":"https:\/\/ileauxnattes.net\/de\/wp-json\/wp\/v2\/pages\/30629\/revisions"}],"predecessor-version":[{"id":31115,"href":"https:\/\/ileauxnattes.net\/de\/wp-json\/wp\/v2\/pages\/30629\/revisions\/31115"}],"wp:attachment":[{"href":"https:\/\/ileauxnattes.net\/de\/wp-json\/wp\/v2\/media?parent=30629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}